{"id":1229,"date":"2022-12-06T10:31:49","date_gmt":"2022-12-06T10:31:49","guid":{"rendered":"https:\/\/www.xano.es\/eyro\/5-strategie-di-ingaggio-e-coinvolgimento\/"},"modified":"2023-03-07T09:59:47","modified_gmt":"2023-03-07T09:59:47","slug":"5-strategie-di-ingaggio-e-coinvolgimento","status":"publish","type":"post","link":"https:\/\/www.eyroproject.eu\/it\/5-strategie-di-ingaggio-e-coinvolgimento\/","title":{"rendered":"5. Strategie di ingaggio e coinvolgimento"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1229\" data-postid=\"1229\" class=\"themify_builder_content themify_builder_content-1229 themify_builder tf_clear\">\n    \t\t\t<!-- module_row -->\n\t<div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_wrtn93 tb_first tf_w tf_clearfix\">\n\t    \t\t\t<div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n\t\t            <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_vo2r93 first\">\n                                                        <div class=\"tb-column-inner tf_box tf_w\">\n                        <!-- module image -->\n<div  class=\"module module-image tb_vhqx146   image-top tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n\t\t    <img decoding=\"async\" src=\"https:\/\/www.alqueriaeducatius.org\/eyro\/wp-content\/uploads\/2022\/12\/5engadgement.jpg\" title=\"5. Strategie di ingaggio e coinvolgimento\" alt=\"5. Strategie di ingaggio e coinvolgimento\">\t\n\t\t<\/div>\n\t<!-- \/image-wrap -->\n    \n    \t<\/div>\n<!-- \/module image --><!-- module text -->\n<div  class=\"module module-text tb_giyh838   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n    \n          <p>Alla fine di questa sessione sar\u00e0 in grado di:<\/p>\n          \n\n          <ol>\n            \n\n            <li>Comprendere i concetti di sensibilizzazione e coinvolgimento;<\/li>\n            \n\n            <li>Riconoscere la differenza tra &#8220;outreach&#8221; e &#8220;engagement&#8221;;<\/li>\n            \n\n            <li>Discutere i vantaggi della sensibilizzazione;<\/li>\n            \n\n            <li>Riconoscere pi\u00f9 efficacemente le esigenze del gruppo target;<\/li>\n            \n\n            <li>Identificare &#8220;buone pratiche&#8221; per motivare i giovani vulnerabili;<\/li>\n            \n\n            <li>Capire come sviluppare efficaci strategie di sensibilizzazione e coinvolgimento a livello locale;<\/li>\n            \n\n          <\/ol>\n            <\/div>\n<\/div>\n<!-- \/module text -->                    <\/div>\n                            <\/div>\n            \t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t<\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Alla fine di questa sessione sar\u00e0 in grado di: Comprendere i concetti di sensibilizzazione e coinvolgimento; Riconoscere la differenza tra &#8220;outreach&#8221; e &#8220;engagement&#8221;; Discutere i vantaggi della sensibilizzazione; Riconoscere pi\u00f9 efficacemente le esigenze del gruppo target; Identificare &#8220;buone pratiche&#8221; per motivare i giovani vulnerabili; Capire come sviluppare efficaci strategie di sensibilizzazione e coinvolgimento a livello [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-1229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<img src=\"https:\/\/www.alqueriaeducatius.org\/eyro\/wp-content\/uploads\/2022\/12\/5engadgement.jpg\" title=\"5. Strategie di ingaggio e coinvolgimento\" alt=\"5. Strategie di ingaggio e coinvolgimento\">\n<p>Alla fine di questa sessione sar\u00e0 in grado di:<\/p> \n <ol> \n <li>Comprendere i concetti di sensibilizzazione e coinvolgimento;<\/li> \n <li>Riconoscere la differenza tra \"outreach\" e \"engagement\";<\/li> \n <li>Discutere i vantaggi della sensibilizzazione;<\/li> \n <li>Riconoscere pi\u00f9 efficacemente le esigenze del gruppo target;<\/li> \n <li>Identificare \"buone pratiche\" per motivare i giovani vulnerabili;<\/li> \n <li>Capire come sviluppare efficaci strategie di sensibilizzazione e coinvolgimento a livello locale;<\/li> \n <\/ol>","_links":{"self":[{"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/posts\/1229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/comments?post=1229"}],"version-history":[{"count":1,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/posts\/1229\/revisions"}],"predecessor-version":[{"id":1230,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/posts\/1229\/revisions\/1230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/media\/477"}],"wp:attachment":[{"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/media?parent=1229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/categories?post=1229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eyroproject.eu\/it\/wp-json\/wp\/v2\/tags?post=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}